{"id":6182,"date":"2021-06-16T22:20:33","date_gmt":"2021-06-16T21:20:33","guid":{"rendered":"https:\/\/www.fattoriamose.com\/informazioni-locali\/"},"modified":"2026-07-25T15:19:44","modified_gmt":"2026-07-25T14:19:44","slug":"informazioni-locali","status":"publish","type":"page","link":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/","title":{"rendered":"Informazioni Locali"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6182\" class=\"elementor elementor-6182 elementor-4951\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55bc024 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"55bc024\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5abf0b6\" data-id=\"5abf0b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1522463 elementor-widget elementor-widget-alloggio_core_section_title\" data-id=\"1522463\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alloggio_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-section-title qodef-alignment--center\">\n\t\t\t<span class=\"qodef-m-text\" style=\"margin-top: 25px\">Agrigento e il suo territorio offrono numerosi siti archeologici, musei, mostre e spettacoli da scoprire durante il soggiorno.<\/span>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec2ba33 qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec2ba33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d525d41\" data-id=\"d525d41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1819d6 elementor-widget elementor-widget-alloggio_core_accordion\" data-id=\"a1819d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alloggio_core_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-accordion clear qodef-behavior--accordion qodef-layout--simple\">\n\t<h3 class=\"qodef-accordion-title\">\n\t<span class=\"qodef-tab-title\">\n\t\tAeroporti e trasporti\t<\/span>\n\t<span class=\"qodef-accordion-mark\">\n\t\t<span class=\"qodef-icon--arrow-down\"><span class=\"qodef-icon-linea-icons icon-arrows-down\" ><\/span><\/span>\n\t\t<span class=\"qodef-icon--arrow-up\"><span class=\"qodef-icon-linea-icons icon-arrows-up\" ><\/span><\/span>\n\t<\/span>\n<\/h3>\n<div class=\"qodef-accordion-content\">\n\t<div class=\"qodef-accordion-content-inner\">\n\t\tSiamo a circa due ore e mezza di auto dagli aeroporti di Palermo e Catania e un po\u2019 meno dall\u2019aeroporto di Trapani.\n\nC\u2019\u00e8 un autobus dall\u2019aeroporto di Catania per Agrigento che parte ogni ora. Ci sono treni e autobus diretti dall\u2019aeroporto di Palermo ad Agrigento.\n\nNon ci sono mezzi pubblici da Trapani-Birgi.\t<\/div>\n<\/div><h3 class=\"qodef-accordion-title\">\n\t<span class=\"qodef-tab-title\">\n\t\tSiti e musei \t<\/span>\n\t<span class=\"qodef-accordion-mark\">\n\t\t<span class=\"qodef-icon--arrow-down\"><span class=\"qodef-icon-linea-icons icon-arrows-down\" ><\/span><\/span>\n\t\t<span class=\"qodef-icon--arrow-up\"><span class=\"qodef-icon-linea-icons icon-arrows-up\" ><\/span><\/span>\n\t<\/span>\n<\/h3>\n<div class=\"qodef-accordion-content\">\n\t<div class=\"qodef-accordion-content-inner\">\n\t\t<p><a href=\"https:\/\/www.lavalledeitempli.it\/\">La Valle dei Templi<\/a> \u00e8 un vasto parco archeologico dichiarato Patrimonio Mondiale dell\u2019UNESCO. Molti ospiti vi trascorrono l\u2019intera giornata. Nei mesi estivi sono molto apprezzate le visite serali ai tre templi principali, con ultimo ingresso intorno alle 19:00. Consultate il loro <a href=\"https:\/\/www.lavalledeitempli.it\/informazioni-turistiche\/orari-biglietti\/\">sito web<\/a> per orari stagionali, eventi, biglietti e altre informazioni.<\/p><p>Il <a href=\"https:\/\/fondoambiente.it\/luoghi\/giardino-della-kolymbethra\">Giardino della Kolymbethra<\/a> si trova all\u2019interno della Valle dei Templi e risale all\u2019epoca in cui Agrigento era la citt\u00e0 greca di Akragas, intorno al 600 a.C. I giardini sono stati restaurati con cura e riaperti nel 2001.<\/p><p>Il <a href=\"https:\/\/parchiarcheologici.regione.sicilia.it\/valle-templi\/siti-archeologici\/museo-archeologico-regionale-pietro-griffo-agrigento\/\">Museo Archeologico<\/a> di Agrigento \u00e8 affascinante e climatizzato. Di particolare interesse sono i frammenti che mostrano i vivaci colori dei templi originali.<\/p><p>La Cattedrale normanna di <a href=\"https:\/\/it.wikipedia.org\/wiki\/Cattedrale_di_San_Gerlando\">San Gerlando<\/a> si trova nella parte alta della citt\u00e0 e, oltre a numerosi reperti storici e artistici, espone una lettera inviata a una suora dal diavolo in persona.<\/p><p>A pochi minuti a piedi dal Duomo si trova l\u2019ancor pi\u00f9 antica Chiesa di Santa Maria dei Greci, costruita sopra un tempio greco dedicato ad Atena, i cui resti sono visibili attraverso il pavimento di vetro.<\/p>\t<\/div>\n<\/div><h3 class=\"qodef-accordion-title\">\n\t<span class=\"qodef-tab-title\">\n\t\tSpiagge \t<\/span>\n\t<span class=\"qodef-accordion-mark\">\n\t\t<span class=\"qodef-icon--arrow-down\"><span class=\"qodef-icon-linea-icons icon-arrows-down\" ><\/span><\/span>\n\t\t<span class=\"qodef-icon--arrow-up\"><span class=\"qodef-icon-linea-icons icon-arrows-up\" ><\/span><\/span>\n\t<\/span>\n<\/h3>\n<div class=\"qodef-accordion-content\">\n\t<div class=\"qodef-accordion-content-inner\">\n\t\t<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Le spiagge pi\u00f9 vicine di Cannatello e San Leone sono a quindici minuti di auto. Sono frequentati soprattutto dalla gente del posto e dalle loro famiglie e sono presenti bar, ristoranti e servizi. Le spiagge sono sabbiose. I fine settimana possono essere impegnativi in \u200b\u200bagosto. Poco pi\u00f9 distanti (30-45 minuti in auto) si trovano le spiagge molto meno affollate di Eraclea Minoa, Siculiana Marina, Giallonardo e la riserva naturale e marina di Torre Salsa. Scala dei Turchi \u00e8 un'ampia scogliera di marna bianca vicino a Porto Empedocle (30 minuti in auto) che figura regolarmente nella Top 10 dei luoghi da visitare in Sicilia.\"><span class=\"Y2IQFc\" lang=\"it\">Le spiagge pi\u00f9 vicine di Cannatello e San Leone sono a quindici minuti di auto. Sono frequentate soprattutto dalla gente del posto e dalle loro famiglie e sono presenti bar, ristoranti e servizi. Le spiagge sono sabbiose. <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Le spiagge pi\u00f9 vicine di Cannatello e San Leone sono a quindici minuti di auto. Sono frequentati soprattutto dalla gente del posto e dalle loro famiglie e sono presenti bar, ristoranti e servizi. Le spiagge sono sabbiose. I fine settimana possono essere impegnativi in \u200b\u200bagosto. Poco pi\u00f9 distanti (30-45 minuti in auto) si trovano le spiagge molto meno affollate di Eraclea Minoa, Siculiana Marina, Giallonardo e la riserva naturale e marina di Torre Salsa. Scala dei Turchi \u00e8 un'ampia scogliera di marna bianca vicino a Porto Empedocle (30 minuti in auto) che figura regolarmente nella Top 10 dei luoghi da visitare in Sicilia.\"><span class=\"Y2IQFc\" lang=\"it\">Poco pi\u00f9 distanti (30-45 minuti in auto) si trovano le spiagge molto meno affollate di Eraclea Minoa, Siculiana Marina, Giallonardo e la riserva naturale e marina di Torre Salsa. <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Le spiagge pi\u00f9 vicine di Cannatello e San Leone sono a quindici minuti di auto. Sono frequentati soprattutto dalla gente del posto e dalle loro famiglie e sono presenti bar, ristoranti e servizi. Le spiagge sono sabbiose. I fine settimana possono essere impegnativi in \u200b\u200bagosto. Poco pi\u00f9 distanti (30-45 minuti in auto) si trovano le spiagge molto meno affollate di Eraclea Minoa, Siculiana Marina, Giallonardo e la riserva naturale e marina di Torre Salsa. Scala dei Turchi \u00e8 un'ampia scogliera di marna bianca vicino a Porto Empedocle (30 minuti in auto) che figura regolarmente nella Top 10 dei luoghi da visitare in Sicilia.\"><span class=\"Y2IQFc\" lang=\"it\"><a href=\"https:\/\/www.visitsicily.info\/scala-dei-turchi\/\">Scala dei Turchi<\/a> \u00e8 un'ampia scogliera di marna bianca vicino a Porto Empedocle (30 minuti in auto) che figura regolarmente tra i dieci luoghi da visitare in Sicilia.<\/span><\/p>\t<\/div>\n<\/div><h3 class=\"qodef-accordion-title\">\n\t<span class=\"qodef-tab-title\">\n\t\tVisite\t<\/span>\n\t<span class=\"qodef-accordion-mark\">\n\t\t<span class=\"qodef-icon--arrow-down\"><span class=\"qodef-icon-linea-icons icon-arrows-down\" ><\/span><\/span>\n\t\t<span class=\"qodef-icon--arrow-up\"><span class=\"qodef-icon-linea-icons icon-arrows-up\" ><\/span><\/span>\n\t<\/span>\n<\/h3>\n<div class=\"qodef-accordion-content\">\n\t<div class=\"qodef-accordion-content-inner\">\n\t\t<div id=\"tw-container\" class=\"nev7se\" data-cp=\"1\" data-is-ver=\"false\" data-nnttsvi=\"1\" data-ntl-fpwrite=\"true\" data-sletp=\"false\" data-sm=\"1\" data-ssbp=\"false\" data-sugg-time=\"500\" data-sugg-url=\"https:\/\/clients1.google.com\/complete\/search\" data-tcp=\"geluk met jou verjaarsdag,gelukkige verjaarsdag,awoda pa,\u1218\u120d\u12ab\u121d \u120d\u12f0\u1275,\u0639\u064a\u062f \u0645\u064a\u0644\u0627\u062f \u0633\u0639\u064a\u062f,\u099c\u09a8\u09cd\u09ae\u09a6\u09bf\u09a8\u09f0 \u0993\u09b2\u0997 \u099c\u09a8\u09be\u09b2\u09cb\u0981,aski mara phuqhawi,do\u011fum g\u00fcn\u00fcn m\u00fcbar\u0259k,ad g\u00fcn\u00fcn m\u00fcbar\u0259k,\u0437 \u0434\u043d\u0451\u043c \u043d\u0430\u0440\u0430\u0434\u0436\u044d\u043d\u043d\u044f,\u0447\u0435\u0441\u0442\u0438\u0442 \u0440\u043e\u0436\u0434\u0435\u043d \u0434\u0435\u043d,\u091c\u0928\u094d\u092e \u0926\u093f\u0928 \u0915\u0947 \u0936\u0941\u092d \u0915\u093e\u092e\u0928\u093e,sanb\u03b5 sanb\u03b5,\u09b6\u09c1\u09ad \u099c\u09a8\u09cd\u09ae\u09a6\u09bf\u09a8,sretan ro\u0111endan,per molts anys,feli\u00e7 aniversari,malipayong adlawng natawhan,\u06cc\u0627\u062f\u06cc \u0644\u06d5\u062f\u0627\u06cc\u06a9 \u0628\u0648\u0648\u0646\u062a \u067e\u06cc\u0631\u06c6\u0632 \u0628\u06ce\u062a,felice anniversariu,v\u0161echno nejlep\u0161\u00ed k narozenin\u00e1m,pen-blwydd hapus,penblwydd hapus,tillykke med f\u00f8dselsdagen,alles gute zum geburtstag,\u0938\u093e\u0932\u0917\u093f\u0930\u0939\u094d \u092e\u092c\u093e\u0930\u0915,\u0787\u07aa\u078a\u07a7\u0788\u07ac\u0783\u07a8 \u0787\u07aa\u078a\u07a6\u0782\u07b0\u078b\u07aa\u0788\u07a6\u0780\u07ac\u0787\u07b0,dzigbe z\u00e3 nyuie na w\u00f2,\u03c7\u03b1\u03c1\u03bf\u03cd\u03bc\u03b5\u03bd\u03b1 \u03b3\u03b5\u03bd\u03ad\u03b8\u03bb\u03b9\u03b1,happy birthday,feli\u0109an naski\u011dtagon,feliz cumplea\u00f1os,palju \u00f5nne s\u00fcnnip\u00e4evaks,zorionak,\u062a\u0648\u0644\u062f\u062a \u0645\u0628\u0627\u0631\u06a9,hyv\u00e4\u00e4 syntym\u00e4p\u00e4iv\u00e4\u00e4,joyeux anniversaire,lokkige jierdei,l\u00e1 breithe sona,l\u00e1 breithe shona duit,co-l\u00e0-breith math,feliz aniversario,vy'apav\u1ebd,\u091c\u0932\u094d\u092e\u0926\u093f\u0938\u093e\u091a\u0940 \u092a\u0930\u092c\u0940,\u0a9c\u0aa8\u0acd\u0aae\u0aa6\u0abf\u0ab5\u0ab8\u0aa8\u0ac0 \u0ab6\u0ac1\u0aad\u0ac7\u0a9a\u0acd\u0a9b\u0abe,\u0a9c\u0aa8\u0acd\u0aae\u0aa6\u0abf\u0ab5\u0ab8 \u0aa8\u0ac0 \u0ab6\u0ac1\u0aad\u0a95\u0abe\u0aae\u0aa8\u0abe,barka da ranar haihuwa,hau\u02bboli l\u0101 h\u0101nau,\u091c\u0928\u094d\u092e\u0926\u093f\u0928 \u0915\u0940 \u0936\u0941\u092d\u0915\u093e\u092e\u0928\u093e\u090f\u0902,\u091c\u0928\u094d\u092e\u0926\u093f\u0928 \u0915\u0940 \u0936\u0941\u092d\u0915\u093e\u092e\u0928\u093e\u090f\u0901,sretan ro\u0111endan,b\u00f2n f\u00e8t,boldog sz\u00fclet\u00e9snapot,\u056e\u0576\u0578\u0582\u0576\u0564\u0564 \u0577\u0576\u0578\u0580\u0570\u0561\u057e\u0578\u0580,selamat ulang tahun,ezi ncheta \u1ee5b\u1ecdch\u1ecb \u1ecdm\u1ee5m\u1ee5,ezi ncheta \u1ecdm\u1ee5m\u1ee5,naragsak a panagkasangay,til hamingju me\u00f0 afm\u00e6li\u00f0,buon compleanno,\u05d9\u05d5\u05dd \u05d4\u05d5\u05dc\u05d3\u05ea \u05e9\u05de\u05d7,\u8a95\u751f\u65e5\u304a\u3081\u3067\u3068\u3046,\u304a\u8a95\u751f\u65e5\u304a\u3081\u3067\u3068\u3046,sugeng ambal warsa,sugeng tanggap warsa,\u10d2\u10d8\u10da\u10dd\u10ea\u10d0\u10d5\u10d7 \u10d3\u10d0\u10d1\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d3\u10e6\u10d4\u10e1,\u10d2\u10d8\u10da\u10dd\u10ea\u10d0\u10d5 \u10d3\u10d0\u10d1\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d3\u10e6\u10d4\u10e1,\u0442\u0443\u0493\u0430\u043d \u043a\u04af\u043d \u049b\u04b1\u0442\u0442\u044b \u0431\u043e\u043b\u0441\u044b\u043d,\u0442\u0443\u044b\u043b\u0493\u0430\u043d \u043a\u04af\u043d\u0456\u04a3\u043c\u0435\u043d,\u179a\u17b8\u1780\u179a\u17b6\u1799\u1790\u17d2\u1784\u17c3\u1781\u17bd\u1794\u1780\u17c6\u178e\u17be\u178f,\u179a\u17b8\u1780\u179a\u17b6\u1799\u200b\u1790\u17d2\u1784\u17c3\u200b\u1780\u17c6\u178e\u17be\u178f,\u0cb9\u0cc1\u0c9f\u0ccd\u0c9f\u0cc1\u0cb9\u0cac\u0ccd\u0cac\u0ca6 \u0cb6\u0cc1\u0cad\u0cbe\u0cb6\u0caf\u0c97\u0cb3\u0cc1,\u0c9c\u0ca8\u0ccd\u0cae\u0ca6\u0cbf\u0ca8\u0ca6 \u0cb6\u0cc1\u0cad\u0cbe\u0cb6\u0caf\u0c97\u0cb3\u0cc1,\uc0dd\uc77c \ucd95\ud558\ud569\ub2c8\ub2e4,\uc0dd\uc77c \ucd95\ud558\ud574\uc694,api batde,rojb\u00fbna te p\u00eeroz be,\u0442\u0443\u0443\u043b\u0433\u0430\u043d \u043a\u04af\u043d\u04af\u04a3\u04af\u0437 \u043c\u0435\u043d\u0435\u043d,\u0442\u0443\u0443\u043b\u0433\u0430\u043d \u043a\u0443\u043d\u0443\u04a3\u0443\u0437 \u043c\u0435\u043d\u0435\u043d \u043a\u0443\u0442\u0442\u0443\u043a\u0442\u0430\u0439\u043c,felix natalis,alles guddes fir de gebuertsdag,amazaalibwa amalungi,mbotama elamu,\u0eaa\u0eb8\u0e81\u0eaa\u0eb1\u0e99\u0ea7\u0eb1\u0e99\u0ec0\u0e81\u0eb5\u0e94,\u0eaa\u0eb8\u0e81\u200b\u0eaa\u0eb1\u0e99\u200b\u0ea7\u0eb1\u0e99\u200b\u0ec0\u0e81\u0eb5\u0e94,su gimtadieniu,piancham chibai,daudz laimes dzim\u0161anas dien\u0101,\u091c\u0928\u094d\u092e\u0926\u093f\u0928\u0915 \u0936\u0941\u092d\u0915\u093e\u092e\u0928\u093e,tratry ny tsingerin-taona,tratry ny tsingerintaona nahaterahana,\u0441\u0440\u0435\u045c\u0435\u043d \u0440\u043e\u0434\u0435\u043d\u0434\u0435\u043d,\u0d1c\u0d28\u0d4d\u0d2e\u0d26\u0d3f\u0d28\u0d3e\u0d36\u0d02\u0d38\u0d15\u0d7e,\u0442\u04e9\u0440\u0441\u04e9\u043d \u04e9\u0434\u0440\u0438\u0439\u043d \u043c\u044d\u043d\u0434 \u0445\u04af\u0440\u0433\u044d\u0435,\u0442\u04e9\u0440\u0441\u04e9\u043d \u04e9\u0434\u0440\u0438\u0439\u043d \u043c\u044d\u043d\u0434,\uabc5\uabe8\uabe1\uabc9\uabe5\uabcf\uabd4\uabd5 \uabc4\uabe3\uabdb\uabc4 \uabc5\uabe8\uabc3\uabe4\uabe0,\u0935\u093e\u0922\u0926\u093f\u0935\u0938\u093e\u091a\u094d\u092f\u093e \u0936\u0941\u092d\u0947\u091a\u094d\u091b\u093e,\u0935\u093e\u0922\u0926\u093f\u0935\u0938\u093e\u091a\u094d\u092f\u093e \u0939\u093e\u0930\u094d\u0926\u093f\u0915 \u0936\u0941\u092d\u0947\u091a\u094d\u091b\u093e,selamat hari lahir,xewqat sbie\u0127 f'g\u0127eluq sninek,\u1015\u103b\u1031\u102c\u103a\u101b\u103d\u103e\u1004\u103a\u1016\u103d\u101a\u103a \u1019\u103d\u1031\u1038\u1014\u1031\u1037\u1016\u103c\u1005\u103a\u1015\u102b\u1005\u1031,\u1015\u103b\u1031\u102c\u103a\u101b\u103d\u103e\u1004\u103a\u1005\u101b\u102c\u1019\u103d\u1031\u1038\u1014\u1031\u1037\u1016\u103c\u1005\u103a\u1015\u102b\u1005\u1031,\u091c\u0928\u094d\u092e \u0926\u093f\u0928\u0915\u094b \u0936\u0941\u092d\u0915\u093e\u092e\u0928\u093e,gefeliciteerd met je verjaardag,gefeliciteerd,gratulerer med dagen,matswalo a mabotse,tsiku labwino lobadwa,baga guyyaa dhaloota kee geesse,\u0b1c\u0b28\u0b4d\u0b2e\u0b26\u0b3f\u0b28\u0b30 \u0b36\u0b41\u0b2d\u0b47\u0b1a\u0b4d\u0b1b\u0b3e,\u0b1c\u0b28\u0b4d\u0b2e\u0b26\u0b3f\u0b28\u0b30 \u0b05\u0b2d\u0b3f\u0b28\u0b28\u0b4d\u0b26\u0b28,\u0a1c\u0a28\u0a2e\u0a26\u0a3f\u0a28 \u0a26\u0a40\u0a06\u0a02 \u0a35\u0a27\u0a3e\u0a08\u0a06\u0a02,\u0a1c\u0a28\u0a2e\u0a26\u0a3f\u0a28 \u0a2e\u0a41\u0a2c\u0a3e\u0a30\u0a15,wszystkiego najlepszego z okazji urodzin,\u06a9\u0644\u06cc\u0632\u0647 \u062f\u06cc \u0646\u06cc\u06a9\u0645\u0631\u063a\u0647,feliz anivers\u00e1rio,punchawniykipi kusikuni,la mul\u021bi ani,\u0441 \u0434\u043d\u0435\u043c \u0440\u043e\u0436\u0434\u0435\u043d\u0438\u044f,isabukuru nziza,\u0936\u0941\u092d\u0902 \u091c\u0928\u094d\u092e\u0926\u093f\u0928\u092e\u094d\u200c,\u062c\u0646\u0645 \u068f\u064a\u0646\u0647\u0646 \u0645\u0628\u0627\u0631\u06aa,\u0dc3\u0dd4\u0db6 \u0d8b\u0db4\u0db1\u0dca \u0daf\u0dd2\u0db1\u0dba\u0d9a\u0dca,v\u0161etko najlep\u0161ie k narodenin\u00e1m,\u0161\u0165astn\u00e9 narodeniny,vse najbolj\u0161e,manuia asofanau,bhavhadhe rinofadza,maalin dhalasheed farxad leh,dhalasho wacan,g\u00ebzuar dit\u00eblindjen,\u0441\u0440\u0435\u045b\u0430\u043d \u0440\u043e\u0452\u0435\u043d\u0434\u0430\u043d,letsatsi le monate la tsoalo,wilujeung milangkala,wilujeung tepang taun,grattis p\u00e5 f\u00f6delsedagen,heri ya siku ya kuzaliwa,\u0baa\u0bbf\u0bb1\u0ba8\u0bcd\u0ba4\u0ba8\u0bbe\u0bb3\u0bcd \u0bb5\u0bbe\u0bb4\u0bcd\u0ba4\u0bcd\u0ba4\u0bc1\u0b95\u0bb3\u0bcd,\u0baa\u0bbf\u0bb1\u0ba8\u0bcd\u0ba4\u0ba8\u0bbe\u0bb3\u0bcd \u0bb5\u0bbe\u0bb4\u0bcd\u0ba4\u0bcd\u0ba4\u0bc1\u0b95\u0bcd\u0b95\u0bb3\u0bcd,\u0c2a\u0c41\u0c1f\u0c4d\u0c1f\u0c3f\u0c28\u0c30\u0c4b\u0c1c\u0c41 \u0c36\u0c41\u0c2d\u0c3e\u0c15\u0c3e\u0c02\u0c15\u0c4d\u0c37\u0c32\u0c41,\u0437\u043e\u0434\u0440\u04ef\u0437 \u043c\u0443\u0431\u043e\u0440\u0430\u043a,\u0e2a\u0e38\u0e02\u0e2a\u0e31\u0e19\u0e15\u0e4c\u0e27\u0e31\u0e19\u0e40\u0e01\u0e34\u0e14,\u12a5\u1295\u12b3\u12d5 \u1270\u12c8\u1208\u12f5\u12ab,doglan g\u00fcn\u00fc\u0148 bilen,maligayang kaarawan,do\u011fum g\u00fcn\u00fcn\u00fcz kutlu olsun,do\u011fum g\u00fcn\u00fcn kutlu olsun,siku lerinene ro velekiwa,\u0442\u0443\u0433\u0430\u043d \u043a\u04e9\u043d \u0431\u0435\u043b\u04d9\u043d,\u0437 \u0434\u043d\u0435\u043c \u043d\u0430\u0440\u043e\u0434\u0436\u0435\u043d\u043d\u044f,\u0633\u0627\u0644\u06af\u0631\u06c1 \u0645\u0628\u0627\u0631\u06a9,\u0633\u0627\u0644\u06af\u0631\u06c1 \u0645\u0628\u0627\u0631\u06a9 \u06c1\u0648,tug\u02bbilgan kuningiz bilan,tug'ilgan kun muborak bo'lsin,ch\u00fac m\u1eebng sinh nh\u1eadt,mini emnandi,nwabela usuku lwakho owaqala ngalo,o ku\u0301 a\u0300ya\u0301j\u1ecd\u0301 \u1ecdj\u1ecd\u0301 i\u0300bi\u0301,o ku ojo ibi,\u751f\u65e5\u5feb\u4e50,\u751f\u65e5\u5feb\u6a02,sikufisela usuku lokuzalwa oluhle,usuku olumnandi lokuzalwa\" data-uilc=\"en\" data-vil=\",af,af-ZA,am,am-ET,ar-EG,ar-AE,ar-KW,ar-QA,ar,ar-IL,ar-JO,ar-LB,ar-PS,az,az-AZ,bg,bg-BG,bn,bn-BD,bn-IN,ca,ca-es,cs,cs-CZ,de,de-DE,de-CH,de-AT,de-LI,en,en-US,en-CA,en-AU,en-NZ,en-GB,en-IN,en-KE,en-TZ,en-NG,en-GH,en-PH,en-ZA,es,es-ES,es-AR,es-UY,es-419,es-BO,es-CL,es-CR,es-CO,es-DO,es-EC,es-GT,es-HN,es-NI,es-PA,es-PE,es-PR,es-PY,es-SV,es-VE,es-MX,es-US,eu,eu-ES,fi,fi-FI,fr,fr-FR,fr-CH,fr-BE,gl,gl-ES,gu,gu-IN,he,he-IL,iw,iw-IL,hu,hu-HU,hy,hy-AM,id,id-ID,is,is-IS,it,it-IT,it-CH,ja,ja-JP,jv,jv-ID,ka,ka-GE,km,km-KH,kn,kn-IN,ko,ko-KR,la,lo,lo-LA,lv,lv-LV,ml,ml-IN,mr,mr-IN,ms,ms-MY,nl,nl-NL,nb,nb-NO,ne,ne-NP,pl,pl-PL,pt,pt-BR,pt-PT,ro,ro-RO,ru,ru-RU,si-LK,sk,sk-SK,sr,sr-RS,su,su-ID,sv,sv-SE,sw,sw-TZ,sw-KE,ta,ta-IN,ta-SG,ta-LK,ta-MY,te,te-IN,tr,tr-TR,ur,ur-PK,ur-IN,yue,yue-HK,yue-Hant-HK,zh-HK,zh,zh-CN,zh-cmn,zh-cmn-CN,zh-Hans,zh-Hans-CN,zh-cmn-Hans,zh-cmn-Hans-CN,cmn-CN,cmn-Hans,cmn-Hans-CN,zh-TW,zh-Hant-TW,cmn-TW,cmn-Hant-TW,zh-cmn-TW,zh-cmn-Hant-TW,zu,zu-ZA,hi,hi-IN,tl,tl-PH,pa,pa-IN\"><div id=\"tw-ob\" class=\"tw-src-ltr\"><div class=\"oSioSc\"><div id=\"tw-target\"><div id=\"kAz1tf\" class=\"g9WsWb PZPZlf\" data-attrid=\"tw-targetArea\" data-entityname=\"Google Translate\"><div id=\"tw-target-text-container\" class=\"tw-ta-container F0azHf tw-nfl\" role=\"text\"><p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Favara e la Fattoria Culturale (8km)\u00a0 Palma di Montechiaro, la cittadina collinare che fu la residenza della famiglia dell'autore del Gattopardo, dove un convento produce ancora i tradizionali dolci di mandorle (20 km). Porto Empedocle, casa letteraria del commissario Montalbano (13km) Scicli, gioiello del barocco e patria cinematografica di Montalbano (135km - 2,5h in auto) Villa del Casale e i suoi mosaici (99km - 1h 40m in auto)\u00a0 Caltagirone e le sue ceramiche (107km - 1h 40m in auto)\u00a0 Modica e il suo cioccolato (141km - 2,5h in auto)\u00a0 Selinunte - templi incontaminati sul mare (99km - 1,5h in auto)\"><span class=\"Y2IQFc\" lang=\"it\">Favara e la <a href=\"https:\/\/www.farmculturalpark.com\/\">Farm<\/a> (8km)\u00a0<\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Favara e la Fattoria Culturale (8km)\u00a0 Palma di Montechiaro, la cittadina collinare che fu la residenza della famiglia dell'autore del Gattopardo, dove un convento produce ancora i tradizionali dolci di mandorle (20 km). Porto Empedocle, casa letteraria del commissario Montalbano (13km) Scicli, gioiello del barocco e patria cinematografica di Montalbano (135km - 2,5h in auto) Villa del Casale e i suoi mosaici (99km - 1h 40m in auto)\u00a0 Caltagirone e le sue ceramiche (107km - 1h 40m in auto)\u00a0 Modica e il suo cioccolato (141km - 2,5h in auto)\u00a0 Selinunte - templi incontaminati sul mare (99km - 1,5h in auto)\"><span class=\"Y2IQFc\" lang=\"it\">Palma di Montechiaro, la cittadina del \"Gattopardo\" dove un convento produce ancora i tradizionali dolci di mandorle (20 km). <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Favara e la Fattoria Culturale (8km)\u00a0 Palma di Montechiaro, la cittadina collinare che fu la residenza della famiglia dell'autore del Gattopardo, dove un convento produce ancora i tradizionali dolci di mandorle (20 km). Porto Empedocle, casa letteraria del commissario Montalbano (13km) Scicli, gioiello del barocco e patria cinematografica di Montalbano (135km - 2,5h in auto) Villa del Casale e i suoi mosaici (99km - 1h 40m in auto)\u00a0 Caltagirone e le sue ceramiche (107km - 1h 40m in auto)\u00a0 Modica e il suo cioccolato (141km - 2,5h in auto)\u00a0 Selinunte - templi incontaminati sul mare (99km - 1,5h in auto)\"><span class=\"Y2IQFc\" lang=\"it\">Porto Empedocle, luogo di nascita di Andrea Camilleri, 'padre' di Montalbano (13km) <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Favara e la Fattoria Culturale (8km)\u00a0 Palma di Montechiaro, la cittadina collinare che fu la residenza della famiglia dell'autore del Gattopardo, dove un convento produce ancora i tradizionali dolci di mandorle (20 km). Porto Empedocle, casa letteraria del commissario Montalbano (13km) Scicli, gioiello del barocco e patria cinematografica di Montalbano (135km - 2,5h in auto) Villa del Casale e i suoi mosaici (99km - 1h 40m in auto)\u00a0 Caltagirone e le sue ceramiche (107km - 1h 40m in auto)\u00a0 Modica e il suo cioccolato (141km - 2,5h in auto)\u00a0 Selinunte - templi incontaminati sul mare (99km - 1,5h in auto)\"><span class=\"Y2IQFc\" lang=\"it\">Scicli, gioiello del barocco e luogo della riprese di Montalbano (135km - 2,5h in auto) <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Favara e la Fattoria Culturale (8km)\u00a0 Palma di Montechiaro, la cittadina collinare che fu la residenza della famiglia dell'autore del Gattopardo, dove un convento produce ancora i tradizionali dolci di mandorle (20 km). Porto Empedocle, casa letteraria del commissario Montalbano (13km) Scicli, gioiello del barocco e patria cinematografica di Montalbano (135km - 2,5h in auto) Villa del Casale e i suoi mosaici (99km - 1h 40m in auto)\u00a0 Caltagirone e le sue ceramiche (107km - 1h 40m in auto)\u00a0 Modica e il suo cioccolato (141km - 2,5h in auto)\u00a0 Selinunte - templi incontaminati sul mare (99km - 1,5h in auto)\"><span class=\"Y2IQFc\" lang=\"it\">Villa del Casale e i suoi mosaici (99km - 1h 40m in auto)\u00a0 <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Favara e la Fattoria Culturale (8km)\u00a0 Palma di Montechiaro, la cittadina collinare che fu la residenza della famiglia dell'autore del Gattopardo, dove un convento produce ancora i tradizionali dolci di mandorle (20 km). Porto Empedocle, casa letteraria del commissario Montalbano (13km) Scicli, gioiello del barocco e patria cinematografica di Montalbano (135km - 2,5h in auto) Villa del Casale e i suoi mosaici (99km - 1h 40m in auto)\u00a0 Caltagirone e le sue ceramiche (107km - 1h 40m in auto)\u00a0 Modica e il suo cioccolato (141km - 2,5h in auto)\u00a0 Selinunte - templi incontaminati sul mare (99km - 1,5h in auto)\"><span class=\"Y2IQFc\" lang=\"it\">Caltagirone e le sue ceramiche (107km - 1h 40m in auto)\u00a0<\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Favara e la Fattoria Culturale (8km)\u00a0 Palma di Montechiaro, la cittadina collinare che fu la residenza della famiglia dell'autore del Gattopardo, dove un convento produce ancora i tradizionali dolci di mandorle (20 km). Porto Empedocle, casa letteraria del commissario Montalbano (13km) Scicli, gioiello del barocco e patria cinematografica di Montalbano (135km - 2,5h in auto) Villa del Casale e i suoi mosaici (99km - 1h 40m in auto)\u00a0 Caltagirone e le sue ceramiche (107km - 1h 40m in auto)\u00a0 Modica e il suo cioccolato (141km - 2,5h in auto)\u00a0 Selinunte - templi incontaminati sul mare (99km - 1,5h in auto)\"><span class=\"Y2IQFc\" lang=\"it\">Modica e il suo cioccolato (141km - 2,5h in auto)<\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Favara e la Fattoria Culturale (8km)\u00a0 Palma di Montechiaro, la cittadina collinare che fu la residenza della famiglia dell'autore del Gattopardo, dove un convento produce ancora i tradizionali dolci di mandorle (20 km). Porto Empedocle, casa letteraria del commissario Montalbano (13km) Scicli, gioiello del barocco e patria cinematografica di Montalbano (135km - 2,5h in auto) Villa del Casale e i suoi mosaici (99km - 1h 40m in auto)\u00a0 Caltagirone e le sue ceramiche (107km - 1h 40m in auto)\u00a0 Modica e il suo cioccolato (141km - 2,5h in auto)\u00a0 Selinunte - templi incontaminati sul mare (99km - 1,5h in auto)\"><span class=\"Y2IQFc\" lang=\"it\">Selinunte - grande sito archeologico (99km - 1,5h in auto)<\/span><\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t<\/div>\n<\/div><h3 class=\"qodef-accordion-title\">\n\t<span class=\"qodef-tab-title\">\n\t\tRistoranti, dolci &amp; gelati \t<\/span>\n\t<span class=\"qodef-accordion-mark\">\n\t\t<span class=\"qodef-icon--arrow-down\"><span class=\"qodef-icon-linea-icons icon-arrows-down\" ><\/span><\/span>\n\t\t<span class=\"qodef-icon--arrow-up\"><span class=\"qodef-icon-linea-icons icon-arrows-up\" ><\/span><\/span>\n\t<\/span>\n<\/h3>\n<div class=\"qodef-accordion-content\">\n\t<div class=\"qodef-accordion-content-inner\">\n\t\t<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: \u00c8 difficile mangiare male in Sicilia. Tuttavia, ecco alcune raccomandazioni locali: Kokalos (6 km). Un ristorante e pizzeria a prezzi ragionevoli con una fantastica vista sul Tempio.\u00a0 ExPanificio (10km). Un buon ristorante in una piazza centrale di Agrigento.\u00a0 Kal\u00f2s (5km). Un raffinato ristorante con terrazza panoramica.\u00a0 Agor\u00e0 (3km). Ottima pasticceria, caffetteria e gelato.\u00a0 La Madia a Licata (37km). Esperienza Michelin 2*.\u00a0 San Leone (4 km) ha ristoranti di pesce buoni e ragionevoli: Il Pescatore; Caico; e il Molo.\"><span class=\"Y2IQFc\" lang=\"it\">\u00c8 difficile mangiare male in Sicilia. Tuttavia, ecco alcune raccomandazioni locali: <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: \u00c8 difficile mangiare male in Sicilia. Tuttavia, ecco alcune raccomandazioni locali: Kokalos (6 km). Un ristorante e pizzeria a prezzi ragionevoli con una fantastica vista sul Tempio.\u00a0 ExPanificio (10km). Un buon ristorante in una piazza centrale di Agrigento.\u00a0 Kal\u00f2s (5km). Un raffinato ristorante con terrazza panoramica.\u00a0 Agor\u00e0 (3km). Ottima pasticceria, caffetteria e gelato.\u00a0 La Madia a Licata (37km). Esperienza Michelin 2*.\u00a0 San Leone (4 km) ha ristoranti di pesce buoni e ragionevoli: Il Pescatore; Caico; e il Molo.\"><span class=\"Y2IQFc\" lang=\"it\"><a href=\"https:\/\/www.ristorante-kokalos.net\/\" target=\"_blank\" rel=\"noopener\">Kokalos<\/a> (6 km). Un ristorante e pizzeria a prezzi ragionevoli con una fantastica vista sulla Valle dei Templi.\u00a0<\/span><\/p><p dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: \u00c8 difficile mangiare male in Sicilia. Tuttavia, ecco alcune raccomandazioni locali: Kokalos (6 km). Un ristorante e pizzeria a prezzi ragionevoli con una fantastica vista sul Tempio.\u00a0 ExPanificio (10km). Un buon ristorante in una piazza centrale di Agrigento.\u00a0 Kal\u00f2s (5km). Un raffinato ristorante con terrazza panoramica.\u00a0 Agor\u00e0 (3km). Ottima pasticceria, caffetteria e gelato.\u00a0 La Madia a Licata (37km). Esperienza Michelin 2*.\u00a0 San Leone (4 km) ha ristoranti di pesce buoni e ragionevoli: Il Pescatore; Caico; e il Molo.\"><a href=\"http:\/\/www.gingerpeoplefood.com\">Ginger<\/a> (10km). Ristorante premiato Siciliano\/Africano nel centro storico di Agrigento.<\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: \u00c8 difficile mangiare male in Sicilia. Tuttavia, ecco alcune raccomandazioni locali: Kokalos (6 km). Un ristorante e pizzeria a prezzi ragionevoli con una fantastica vista sul Tempio.\u00a0 ExPanificio (10km). Un buon ristorante in una piazza centrale di Agrigento.\u00a0 Kal\u00f2s (5km). Un raffinato ristorante con terrazza panoramica.\u00a0 Agor\u00e0 (3km). Ottima pasticceria, caffetteria e gelato.\u00a0 La Madia a Licata (37km). Esperienza Michelin 2*.\u00a0 San Leone (4 km) ha ristoranti di pesce buoni e ragionevoli: Il Pescatore; Caico; e il Molo.\"><span class=\"Y2IQFc\" lang=\"it\"><a href=\"http:\/\/www.osteriaexpanificio.it\/\" target=\"_blank\" rel=\"noopener\">ExPanificio<\/a> (10km). Un buon ristorante in una piazza centrale di Agrigento.\u00a0 <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: \u00c8 difficile mangiare male in Sicilia. Tuttavia, ecco alcune raccomandazioni locali: Kokalos (6 km). Un ristorante e pizzeria a prezzi ragionevoli con una fantastica vista sul Tempio.\u00a0 ExPanificio (10km). Un buon ristorante in una piazza centrale di Agrigento.\u00a0 Kal\u00f2s (5km). Un raffinato ristorante con terrazza panoramica.\u00a0 Agor\u00e0 (3km). Ottima pasticceria, caffetteria e gelato.\u00a0 La Madia a Licata (37km). Esperienza Michelin 2*.\u00a0 San Leone (4 km) ha ristoranti di pesce buoni e ragionevoli: Il Pescatore; Caico; e il Molo.\"><span class=\"Y2IQFc\" lang=\"it\"><a href=\"http:\/\/ristorantekalos.it\/en\/home-eng\/\" target=\"_blank\" rel=\"noopener\">Kal\u00f2s<\/a> (5km). Un raffinato ristorante con terrazza panoramica.\u00a0 <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: \u00c8 difficile mangiare male in Sicilia. Tuttavia, ecco alcune raccomandazioni locali: Kokalos (6 km). Un ristorante e pizzeria a prezzi ragionevoli con una fantastica vista sul Tempio.\u00a0 ExPanificio (10km). Un buon ristorante in una piazza centrale di Agrigento.\u00a0 Kal\u00f2s (5km). Un raffinato ristorante con terrazza panoramica.\u00a0 Agor\u00e0 (3km). Ottima pasticceria, caffetteria e gelato.\u00a0 La Madia a Licata (37km). Esperienza Michelin 2*.\u00a0 San Leone (4 km) ha ristoranti di pesce buoni e ragionevoli: Il Pescatore; Caico; e il Molo.\"><span class=\"Y2IQFc\" lang=\"it\"><a href=\"https:\/\/www.pasticceria-agora.it\/\" target=\"_blank\" rel=\"noopener\">Agor\u00e0<\/a>\u00a0(3km). Ottima pasticceria, caffetteria e gelato.\u00a0 <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: \u00c8 difficile mangiare male in Sicilia. Tuttavia, ecco alcune raccomandazioni locali: Kokalos (6 km). Un ristorante e pizzeria a prezzi ragionevoli con una fantastica vista sul Tempio.\u00a0 ExPanificio (10km). Un buon ristorante in una piazza centrale di Agrigento.\u00a0 Kal\u00f2s (5km). Un raffinato ristorante con terrazza panoramica.\u00a0 Agor\u00e0 (3km). Ottima pasticceria, caffetteria e gelato.\u00a0 La Madia a Licata (37km). Esperienza Michelin 2*.\u00a0 San Leone (4 km) ha ristoranti di pesce buoni e ragionevoli: Il Pescatore; Caico; e il Molo.\"><span class=\"Y2IQFc\" lang=\"it\"><a href=\"https:\/\/www.ristorantelamadia.it\/\" target=\"_blank\" rel=\"noopener\">La Madia a Licata<\/a> (37km).<\/span><span class=\"Y2IQFc\" lang=\"it\"> Ristorante Michelin.\u00a0 <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: \u00c8 difficile mangiare male in Sicilia. Tuttavia, ecco alcune raccomandazioni locali: Kokalos (6 km). Un ristorante e pizzeria a prezzi ragionevoli con una fantastica vista sul Tempio.\u00a0 ExPanificio (10km). Un buon ristorante in una piazza centrale di Agrigento.\u00a0 Kal\u00f2s (5km). Un raffinato ristorante con terrazza panoramica.\u00a0 Agor\u00e0 (3km). Ottima pasticceria, caffetteria e gelato.\u00a0 La Madia a Licata (37km). Esperienza Michelin 2*.\u00a0 San Leone (4 km) ha ristoranti di pesce buoni e ragionevoli: Il Pescatore; Caico; e il Molo.\"><span class=\"Y2IQFc\" lang=\"it\">San Leone (4 km) ha ristoranti di pesce buoni e ragionevoli: Il Pescatore; Caico; e il Molo.<\/span><\/p><p>Le Cuspidi, ottimo gelato a San Leone, Agrigento e Raffadali.<\/p>\t<\/div>\n<\/div><h3 class=\"qodef-accordion-title\">\n\t<span class=\"qodef-tab-title\">\n\t\tPasseggiate in Fattoria\t<\/span>\n\t<span class=\"qodef-accordion-mark\">\n\t\t<span class=\"qodef-icon--arrow-down\"><span class=\"qodef-icon-linea-icons icon-arrows-down\" ><\/span><\/span>\n\t\t<span class=\"qodef-icon--arrow-up\"><span class=\"qodef-icon-linea-icons icon-arrows-up\" ><\/span><\/span>\n\t<\/span>\n<\/h3>\n<div class=\"qodef-accordion-content\">\n\t<div class=\"qodef-accordion-content-inner\">\n\t\t<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Le immagini sottostanti mostrano percorsi intorno alla fattoria compresi tra 1,5 km e 4 km. Lungo il percorso si trovano ulivi millenari, mandorli, pistacchi e carrubi. Il percorso pi\u00f9 breve \u00e8 in leggera pendenza e pu\u00f2 essere percorso in venti-trenta minuti. Gli altri sono pi\u00f9 lunghi e adatti ai corridori.\"><span class=\"Y2IQFc\" lang=\"it\">Le immagini qui sotto mostrano percorsi all'interno dell'azienda agricola tra 1,5 km e 4 km. <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Le immagini sottostanti mostrano percorsi intorno alla fattoria compresi tra 1,5 km e 4 km. Lungo il percorso si trovano ulivi millenari, mandorli, pistacchi e carrubi. Il percorso pi\u00f9 breve \u00e8 in leggera pendenza e pu\u00f2 essere percorso in venti-trenta minuti. Gli altri sono pi\u00f9 lunghi e adatti ai corridori.\"><span class=\"Y2IQFc\" lang=\"it\">Lungo il percorso si trovano ulivi millenari, mandorli, pistacchi e carrubi. Il percorso pi\u00f9 breve \u00e8 in leggera pendenza e pu\u00f2 essere percorso in venti-trenta minuti.<\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Le immagini sottostanti mostrano percorsi intorno alla fattoria compresi tra 1,5 km e 4 km. Lungo il percorso si trovano ulivi millenari, mandorli, pistacchi e carrubi. Il percorso pi\u00f9 breve \u00e8 in leggera pendenza e pu\u00f2 essere percorso in venti-trenta minuti. Gli altri sono pi\u00f9 lunghi e adatti ai corridori.\"><span class=\"Y2IQFc\" lang=\"it\">Gli altri sono pi\u00f9 lunghi.<\/span><\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-5382 size-full\" src=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01.jpg\" alt=\"\" width=\"800\" height=\"573\" srcset=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01.jpg 800w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01-300x215.jpg 300w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01-768x550.jpg 768w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01-600x430.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p><p><img decoding=\"async\" class=\"alignnone wp-image-5386 size-full\" src=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk02.jpg\" alt=\"\" width=\"800\" height=\"573\" srcset=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk02.jpg 800w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk02-300x215.jpg 300w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk02-768x550.jpg 768w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk02-600x430.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p><p><img decoding=\"async\" class=\"alignnone wp-image-5384 size-full\" src=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk03.jpg\" alt=\"\" width=\"800\" height=\"573\" srcset=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk03.jpg 800w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk03-300x215.jpg 300w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk03-768x550.jpg 768w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk03-600x430.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5383 size-full\" src=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk04.jpg\" alt=\"\" width=\"800\" height=\"573\" srcset=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk04.jpg 800w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk04-300x215.jpg 300w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk04-768x550.jpg 768w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk04-600x430.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\t<\/div>\n<\/div><h3 class=\"qodef-accordion-title\">\n\t<span class=\"qodef-tab-title\">\n\t\tShopping\t<\/span>\n\t<span class=\"qodef-accordion-mark\">\n\t\t<span class=\"qodef-icon--arrow-down\"><span class=\"qodef-icon-linea-icons icon-arrows-down\" ><\/span><\/span>\n\t\t<span class=\"qodef-icon--arrow-up\"><span class=\"qodef-icon-linea-icons icon-arrows-up\" ><\/span><\/span>\n\t<\/span>\n<\/h3>\n<div class=\"qodef-accordion-content\">\n\t<div class=\"qodef-accordion-content-inner\">\n\t\t<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Il Villaggio Mos\u00e8 \u00e8 a 1 km di distanza e dispone di numerose panetterie, supermercati, negozi, ristoranti e bar. C'\u00e8 un mercato settimanale il luned\u00ec mattina al Villaggio Mos\u00e9 (15 minuti a piedi) e uno pi\u00f9 grande ad Agrigento e un altro a Favara il venerd\u00ec.\"><span class=\"Y2IQFc\" lang=\"it\">Villaggio Mos\u00e8 \u00e8 a 1 km di distanza e dispone di numerose panetterie, supermercati, negozi, ristoranti e bar. <\/span><\/p><p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwjWgajSsoKLAxWezwIHHXyoJS4Q3ewLegQIBxAU\" aria-label=\"Translated text: Il Villaggio Mos\u00e8 \u00e8 a 1 km di distanza e dispone di numerose panetterie, supermercati, negozi, ristoranti e bar. C'\u00e8 un mercato settimanale il luned\u00ec mattina al Villaggio Mos\u00e9 (15 minuti a piedi) e uno pi\u00f9 grande ad Agrigento e un altro a Favara il venerd\u00ec.\"><span class=\"Y2IQFc\" lang=\"it\">C'\u00e8 un mercato settimanale il luned\u00ec mattina al Villaggio Mos\u00e9 (15 minuti a piedi). Il Venerdi mattina ci sono mercati pi\u00f9 grandi ad Agrigento ed a Favara.<\/span><\/p>\t<\/div>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-507ab0f elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"507ab0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c4fab28\" data-id=\"c4fab28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-903a4d3 elementor-widget elementor-widget-image\" data-id=\"903a4d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/agrigento_mose_wisteria_courtyard.jpg\" class=\"attachment-large size-large wp-image-5999\" alt=\"Stunning courtyard with flowering tree at Fattoria Mose\" srcset=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/agrigento_mose_wisteria_courtyard.jpg 960w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/agrigento_mose_wisteria_courtyard-300x200.jpg 300w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/agrigento_mose_wisteria_courtyard-768x512.jpg 768w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/agrigento_mose_wisteria_courtyard-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c84a0cb\" data-id=\"c84a0cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5f4b44 elementor-widget elementor-widget-image\" data-id=\"d5f4b44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/farmstay_fattoria_mose_almonds.jpg\" class=\"attachment-large size-large wp-image-6001\" alt=\"Almonds growing in the garden of Fattoria Mose\" srcset=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/farmstay_fattoria_mose_almonds.jpg 960w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/farmstay_fattoria_mose_almonds-300x200.jpg 300w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/farmstay_fattoria_mose_almonds-768x512.jpg 768w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/farmstay_fattoria_mose_almonds-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe866d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"fe866d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-de8004c\" data-id=\"de8004c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0dd4325 elementor-widget elementor-widget-image\" data-id=\"0dd4325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/mose_agriturismo_sicily_cat.jpg\" class=\"attachment-large size-large wp-image-6000\" alt=\"Grey cat at Fattoria Mose\" srcset=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/mose_agriturismo_sicily_cat.jpg 960w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/mose_agriturismo_sicily_cat-300x200.jpg 300w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/mose_agriturismo_sicily_cat-768x512.jpg 768w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/mose_agriturismo_sicily_cat-600x400.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f826d25\" data-id=\"f826d25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-485675e elementor-widget elementor-widget-image\" data-id=\"485675e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/fattoria_mose_chapel_agrigento.jpg\" class=\"attachment-large size-large wp-image-5998\" alt=\"View of the garden and chapel at Fattoria Mose\" srcset=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/fattoria_mose_chapel_agrigento.jpg 720w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/fattoria_mose_chapel_agrigento-300x200.jpg 300w, https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/fattoria_mose_chapel_agrigento-600x400.jpg 600w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbcf8be elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"bbcf8be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-943621b\" data-id=\"943621b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Agrigento e il suo territorio offrono numerosi siti archeologici, musei, mostre e spettacoli da scoprire durante il soggiorno. Aeroporti e trasporti Siamo a circa due ore e mezza di auto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"class_list":["post-6182","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informazioni Locali - Fattoria Mos\u00e8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informazioni Locali - Fattoria Mos\u00e8\" \/>\n<meta property=\"og:description\" content=\"Agrigento e il suo territorio offrono numerosi siti archeologici, musei, mostre e spettacoli da scoprire durante il soggiorno. Aeroporti e trasporti Siamo a circa due ore e mezza di auto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/\" \/>\n<meta property=\"og:site_name\" content=\"Fattoria Mos\u00e8\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/en-gb.facebook.com\/FattoriaMoseAgriturismo\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-25T14:19:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/informazioni-locali\\\/\",\"url\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/informazioni-locali\\\/\",\"name\":\"Informazioni Locali - Fattoria Mos\u00e8\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/informazioni-locali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/informazioni-locali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fattoriamose.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/fattoria_mose_walk01.jpg\",\"datePublished\":\"2021-06-16T21:20:33+00:00\",\"dateModified\":\"2026-07-25T14:19:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/informazioni-locali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/informazioni-locali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/informazioni-locali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fattoriamose.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/fattoria_mose_walk01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fattoriamose.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/fattoria_mose_walk01.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/informazioni-locali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informazioni Locali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/\",\"name\":\"Fattoria Mos\u00e8\",\"description\":\"Un agriturismo biologico vicino ad Agrigento Valle dei Templi in Sicilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/#organization\",\"name\":\"Fattoria Mos\u00e8\",\"url\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fattoriamose.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Fattoria_Mose_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fattoriamose.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Fattoria_Mose_logo.png\",\"width\":200,\"height\":50,\"caption\":\"Fattoria Mos\u00e8\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fattoriamose.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/en-gb.facebook.com\\\/FattoriaMoseAgriturismo\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informazioni Locali - Fattoria Mos\u00e8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/","og_locale":"it_IT","og_type":"article","og_title":"Informazioni Locali - Fattoria Mos\u00e8","og_description":"Agrigento e il suo territorio offrono numerosi siti archeologici, musei, mostre e spettacoli da scoprire durante il soggiorno. Aeroporti e trasporti Siamo a circa due ore e mezza di auto [&hellip;]","og_url":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/","og_site_name":"Fattoria Mos\u00e8","article_publisher":"https:\/\/en-gb.facebook.com\/FattoriaMoseAgriturismo\/","article_modified_time":"2026-07-25T14:19:44+00:00","og_image":[{"url":"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/","url":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/","name":"Informazioni Locali - Fattoria Mos\u00e8","isPartOf":{"@id":"https:\/\/www.fattoriamose.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/#primaryimage"},"image":{"@id":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01.jpg","datePublished":"2021-06-16T21:20:33+00:00","dateModified":"2026-07-25T14:19:44+00:00","breadcrumb":{"@id":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/#primaryimage","url":"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01.jpg","contentUrl":"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/10\/fattoria_mose_walk01.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fattoriamose.com\/it\/informazioni-locali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fattoriamose.com\/it\/"},{"@type":"ListItem","position":2,"name":"Informazioni Locali"}]},{"@type":"WebSite","@id":"https:\/\/www.fattoriamose.com\/it\/#website","url":"https:\/\/www.fattoriamose.com\/it\/","name":"Fattoria Mos\u00e8","description":"Un agriturismo biologico vicino ad Agrigento Valle dei Templi in Sicilia","publisher":{"@id":"https:\/\/www.fattoriamose.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fattoriamose.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fattoriamose.com\/it\/#organization","name":"Fattoria Mos\u00e8","url":"https:\/\/www.fattoriamose.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fattoriamose.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/Fattoria_Mose_logo.png","contentUrl":"https:\/\/www.fattoriamose.com\/wp-content\/uploads\/2021\/06\/Fattoria_Mose_logo.png","width":200,"height":50,"caption":"Fattoria Mos\u00e8"},"image":{"@id":"https:\/\/www.fattoriamose.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/en-gb.facebook.com\/FattoriaMoseAgriturismo\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.fattoriamose.com\/it\/wp-json\/wp\/v2\/pages\/6182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fattoriamose.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fattoriamose.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fattoriamose.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fattoriamose.com\/it\/wp-json\/wp\/v2\/comments?post=6182"}],"version-history":[{"count":230,"href":"https:\/\/www.fattoriamose.com\/it\/wp-json\/wp\/v2\/pages\/6182\/revisions"}],"predecessor-version":[{"id":7669,"href":"https:\/\/www.fattoriamose.com\/it\/wp-json\/wp\/v2\/pages\/6182\/revisions\/7669"}],"wp:attachment":[{"href":"https:\/\/www.fattoriamose.com\/it\/wp-json\/wp\/v2\/media?parent=6182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}